{"id":819,"count":6,"description":"","link":"https:\/\/exim.com.my\/development\/mgc-categories\/seminars-en\/","name":"Seminars","slug":"seminars-en","taxonomy":"mgc-categories","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/mgc-categories\/819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/mgc-categories"}],"about":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/taxonomies\/mgc-categories"}],"wp:post_type":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/posts?mgc-categories=819"},{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/mgc-events?mgc-categories=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}