{"id":9781,"date":"2022-07-22T14:48:33","date_gmt":"2022-07-22T06:48:33","guid":{"rendered":"https:\/\/exim.com.my\/development\/?page_id=9781"},"modified":"2023-05-19T17:56:49","modified_gmt":"2023-05-19T09:56:49","slug":"soalan-lazim","status":"publish","type":"page","link":"https:\/\/exim.com.my\/development\/soalan-lazim\/","title":{"rendered":"Soalan Lazim"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9781\" class=\"elementor elementor-9781\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b83fe16 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"b83fe16\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ac2f0bd\" data-id=\"ac2f0bd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdb9eb5 elementor-widget__width-auto sub-navi elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-tp-navigation-menu\" data-id=\"bdb9eb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"tp-navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"plus-navigation-wrap text-left nav-menu6a03d04c46e8cbdb9eb5\">\n\t\t\t<div class=\"plus-navigation-inner menu-click main-menu-indicator-none sub-menu-indicator-none plus-menu-style-1\"  data-menu_transition=\"style-1\" data-mobile-menu-click=\"no\">\n\t\t\t\t<div id=\"theplus-navigation-normal-menu\" class=\"collapse navbar-collapse navbar-ex1-collapse\">\n\t\t\t\t\n\t\t\t\t\t<div class=\"plus-navigation-menu menu-vertical  \">\n\t\t\t\t\t\t<ul id=\"menu-resource-centre-sub-menu-bm\" class=\"nav navbar-nav yamm menu-hover-none  \"><li id=\"menu-item-7673\" class=\"menu-item menu-item-type-post_type menu-item-object-page animate-dropdown menu-item-7673 plus-dropdown-menu-\" ><a title=\"Berita dan Peristiwa\" href=\"https:\/\/exim.com.my\/development\/berita-dan-peristiwa\/\" data-text=\"Berita dan Peristiwa\">Berita dan Peristiwa<\/a><\/li>\n<li id=\"menu-item-7674\" class=\"menu-item menu-item-type-post_type menu-item-object-page animate-dropdown menu-item-7674 plus-dropdown-menu-\" ><a title=\"Kenyataan Akhbar\" href=\"https:\/\/exim.com.my\/development\/kenyataan-akhbar\/\" data-text=\"Kenyataan Akhbar\">Kenyataan Akhbar<\/a><\/li>\n<li id=\"menu-item-7675\" class=\"menu-item menu-item-type-post_type menu-item-object-page animate-dropdown menu-item-7675 plus-dropdown-menu-\" ><a title=\"Laporan Tahunan\" href=\"https:\/\/exim.com.my\/development\/laporan-tahunan\/\" data-text=\"Laporan Tahunan\">Laporan Tahunan<\/a><\/li>\n<li id=\"menu-item-7677\" class=\"menu-item menu-item-type-post_type menu-item-object-page animate-dropdown menu-item-7677 plus-dropdown-menu-\" ><a title=\"Galeri Multimedia\" href=\"https:\/\/exim.com.my\/development\/galeri-multimedia\/\" data-text=\"Galeri Multimedia\">Galeri Multimedia<\/a><\/li>\n<li id=\"menu-item-7676\" class=\"menu-item menu-item-type-post_type menu-item-object-page animate-dropdown menu-item-7676 plus-dropdown-menu-\" ><a title=\"Tinjauan\" href=\"https:\/\/exim.com.my\/development\/tinjauan\/\" data-text=\"Tinjauan\">Tinjauan<\/a><\/li>\n<li id=\"menu-item-9872\" class=\"menu-item menu-item-type-post_type menu-item-object-page animate-dropdown menu-item-9872 plus-dropdown-menu-\" ><a title=\"Soalan Lazim\" href=\"https:\/\/exim.com.my\/development\/soalan-lazim\/\" data-text=\"Soalan Lazim\">Soalan Lazim<\/a><\/li>\n<\/ul>\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"plus-mobile-nav-toggle navbar-header mobile-toggle\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"mobile-plus-toggle-menu  plus-collapsed toggle-style-1\"  data-target=\"#plus-mobile-nav-toggle-nav-menu6a03d04c46e8cbdb9eb5\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<ul class=\"toggle-lines\"><li class=\"toggle-line\"><\/li><li class=\"toggle-line\"><\/li><\/ul>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t\t<div id=\"plus-mobile-nav-toggle-nav-menu6a03d04c46e8cbdb9eb5\" class=\"plus-mobile-menu   collapse navbar-collapse navbar-ex1-collapse plus-mobile-menu-content \">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t \n\t\t<style>.plus-navigation-wrap.nav-menu6a03d04c46e8cbdb9eb5 #theplus-navigation-normal-menu{display: block!important;}<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba7e9b5 elementor-widget__width-auto elementor-absolute elementor-view-default ob-has-background-overlay elementor-widget elementor-widget-icon\" data-id=\"ba7e9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-arrow-right\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ef86a3\" data-id=\"1ef86a3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da95ccf elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-invisible\" data-id=\"da95ccf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInDown&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bc01f8f\" data-id=\"bc01f8f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-931ab1e elementor-widget__width-auto inner-title ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"931ab1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>SOALAN LAZIM<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3d6786 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3d6786\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7afb53\" data-id=\"b7afb53\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09d0543 main-title premium-type-column elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-premium-icon-list\" data-id=\"09d0543\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;rbadges_repeater&quot;:[],&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"premium-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<ul class=\"premium-bullet-list-box\">\r\n\t\t\t\t\r\n\t\t\t\t\t\t\t<li class=\"premium-bullet-list-content elementor-repeater-item-84b979c\">\r\n\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-wrapper premium-bullet-list-wrapper-top \">\r\n\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" data-src=\"https:\/\/exim.com.my\/development\/wp-content\/uploads\/2022\/07\/line-element.svg\" alt=\"line-element\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\">\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t<div class=\"premium-bullet-list-text-wrapper\">\r\n\t\t\t\t\t\t\t\t\t\t<span class=\"premium-bullet-text\" data-text=\"Soalan Lazim\"> Soalan Lazim <\/span>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/li>\r\n\r\n\t\t\t\t\t\t\t\t\t\t<\/ul>\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d90962 elementor-tabs-view-horizontal elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-tp-tabs-tours\" data-id=\"2d90962\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"tp-tabs-tours.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"theplus-tabs-wrapper  elementor-tabs   swiper-container swiper-free-mode   \" id=\"tabs6a03d04c95932\" data-tabs-id=\"tabs6a03d04c95932\"  data-connection=\"\"   data-tab-default=\"0\" data-tab-hover=\"no\"data-swiper-loop ='no'  role=\"tablist\"><div class=\"theplus-tabs-nav-wrapper elementor-tabs-wrapper text-left align-top swiper-wrapper  \"><ul class=\"plus-tabs-nav     swiper-slide swiper-slide-active \"><li class=\"\"><div id=\"elementor-tab-title-4771\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"1\" tabindex=\"4771\" role=\"tab\" aria-controls=\"elementor-tab-content-4771\"><span>Rentas <br> Sempadan<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-4772\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"2\" tabindex=\"4772\" role=\"tab\" aria-controls=\"elementor-tab-content-4772\"><span>Pembiayaan <br> Perdagangan<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-4773\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"3\" tabindex=\"4773\" role=\"tab\" aria-controls=\"elementor-tab-content-4773\"><span>Jaminan<\/span><\/div><\/li><li class=\"\"><div id=\"elementor-tab-title-4774\" class=\"elementor-tab-title elementor-tab-desktop-title plus-tab-header \" data-tab=\"4\" tabindex=\"4774\" role=\"tab\" aria-controls=\"elementor-tab-content-4774\"><span>Takaful <br> Kredit<\/span><\/div><\/li><\/ul><\/div><div class=\"theplus-tabs-content-wrapper  elementor-tabs-content-wrapper\"><div class=\"elementor-tab-title elementor-tab-mobile-title text-left \" tabindex=\"4771\" data-tab=\"1\" role=\"tab\"><span>Rentas <br> Sempadan<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"1\" role=\"tabpanel\"><div class=\"plus-content-editor\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9915\" class=\"elementor elementor-9915\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a4a39cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a4a39cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50e3b6bd\" data-id=\"50e3b6bd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cce2f70 faq elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-tp-accordion\" data-id=\"cce2f70\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"theplus-accordion-wrapper elementor-accordion   \"\n    id=\"accordion6a03d04d09d2e\" data-accordion-id=\"accordion6a03d04d09d2e\"\n    data-connection=\"\"\n    data-accordion-type=\"accordion\"\n    data-heightlight-text       role=\"tablist\" >\n\n            <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2141\" class=\"elementor-tab-title plus-accordion-header active-default text-left \" data-tab=\"1\" aria-controls=\"elementor-tab-content-2141\">\n                                \n                <span style=\"width:100%\">Apakah yang Dimaksudkan dengan Pembiayaan Rentas Sempadan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2141\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content active-default \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2141\">\n                <div class=\"plus-content-editor\" ><p>Kemudahan pembiayaan yang diberikan kepada pelanggan yang berhasrat menceburi dalam perniagaan rentas sempadan.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2142\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"2\" aria-controls=\"elementor-tab-content-2142\">\n                                \n                <span style=\"width:100%\">Pakah Produk Pembiayaan Rentas Sempadan yang Ditawarkan oleh EXIM Bank?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2142\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2142\">\n                <div class=\"plus-content-editor\" ><ol><li>Pembiayaan Projek\/Pelaburan Luar Negara-i<\/li><li>Pembiayaan Kontrak-i<\/li><li>Pembiayaan Pembeli-i<\/li><li>Kemudahan Pembiayaan MalaysiaKitchen-i<\/li><li>Pembiayaan Berjangka-i<\/li><li>Pembiayaan Eksport Perkhidmatan-i<\/li><li>Pembiayaan Import-i<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2143\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"3\" aria-controls=\"elementor-tab-content-2143\">\n                                \n                <span style=\"width:100%\">Siapakah yang Layak untuk Memohon Produk Pembiayaan Rentas Sempadan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2143\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2143\">\n                <div class=\"plus-content-editor\" ><p><strong>Pembiayaan Projek\/Pelaburan Luar Negara-i<\/strong><\/p><ol><li>Pembekal\/kontraktor\/pelabur Malaysia.<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembiayaan Kontrak-i<\/strong><\/p><ol><li>Pembekal\/kontraktor Malaysia.<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembiayaan Pembeli-i<\/strong><\/p><ol><li>Pembeli komersial asing atau pembeli kerajaan asing.<\/li><\/ol><p>\u00a0<\/p><p><strong>Kemudahan Pembiayaan MalaysiaKitchen-i<\/strong><\/p><ol><li>Syarikat milik warganegara Malaysia dan\/atau syarikat kawalan diperbadankan di Malaysia dengan pegangan saham minima 51%<\/li><li>Pengalaman kerja berkaitan sama ada setahun (1) tahun dalam pengurusan restoran Luar Negara atau tiga (3) tahun Dalam Negara<\/li><li>Terbuka kepada francais milik warganegara Malaysia<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembiayaan Berjangka-i<\/strong><\/p><ol><li>Pengeksport Malaysia berdaftar di bawah Akta Syarikat 2016<\/li><li>Syarikat Kawalan Bukan Pemastautin<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembiayaan Eksport Perkhidmatan-i<\/strong><\/p><ol><li>Pengeksport Malaysia berdaftar di bawah Akta Syarikat 2016<\/li><li>Syarikat Kawalan Bukan Pemastautin<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembiayaan Import-i<\/strong><\/p><ol><li>Syarikat milik warganegara Malaysia atau syarikat kawalan diperbadankan di Malaysia<\/li><li>Syarikat usaha sama diantara Malaysia dan syarikat asing dengan pemilikan oleh warganegara Malaysia tidak kurang daripada 51% syarikat usaha sama tersebut<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2144\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"4\" aria-controls=\"elementor-tab-content-2144\">\n                                \n                <span style=\"width:100%\">Bagaimanakah Saya Boleh Memohon Produk Pembiayaan Rentas Sempadan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2144\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2144\">\n                <div class=\"plus-content-editor\" ><p>Anda boleh menghubungi kami di +603-2601 2000 untuk bercakap dengan Pengurus Perhubungan untuk maklumat lanjut.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2145\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"5\" aria-controls=\"elementor-tab-content-2145\">\n                                \n                <span style=\"width:100%\">Apakah Kelayakan untuk Pembiayaan EXIM Bank?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2145\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2145\">\n                <div class=\"plus-content-editor\" ><p>Pengeksport atau kontraktor hendaklah dimiliki oleh warganegara Malaysia dan syarikat kawalan kecuali untuk kemudahan Pembiayaan Pembeli-i di mana Pelanggan hendaklah sebuah kerajaan atau syarikat asing.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2146\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"6\" aria-controls=\"elementor-tab-content-2146\">\n                                \n                <span style=\"width:100%\">Apakah Konsep Syariah yang Diguna Pakai dalam Produk Pembiayaan Rentas Sempadan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2146\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2146\">\n                <div class=\"plus-content-editor\" ><ol><li>Ijarah<\/li><li>Istisna\u2019<\/li><li>Murabahah<\/li><li>Tawarruq (Komoditi Murabahah)<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2147\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"7\" aria-controls=\"elementor-tab-content-2147\">\n                                \n                <span style=\"width:100%\">Berapakah Kos untuk Memohon Pembiayaan Rentas Sempadan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2147\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2147\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\">Fi pemprosesan sebanyak 1.0%* dikenakan daripada jumlah pembiayaan. Nota: (*) Tertakluk kepada Terma dan Syarat.<\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2148\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"8\" aria-controls=\"elementor-tab-content-2148\">\n                                \n                <span style=\"width:100%\">Berapa Lamakah Masa yang Diambil oleh EXIM Bank untuk Memproses dan Menyampaikan Keputusan Keatas Permohonan Pembiayaan Rentas Sempadan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2148\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2148\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\">Biasanya ia mengambil masa kira kira 45 hari (21 hari untuk MKFF-i) daripada tarikh permohonan (tertakluk kepada maklumat dan dokumen lengkap yang dikemukakan).<\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2149\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"9\" aria-controls=\"elementor-tab-content-2149\">\n                                \n                <span style=\"width:100%\">Berapakah Margin Pembiayaan untuk Pembiayaan Projek \/ Pelaburan Luar Negara dan Pembiayaan Kontrak?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2149\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2149\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\"><ol><li>Pembiayaan Projek Luar Negara-i : sehingga 85% daripada nilai projek<\/li><li>Pembiayaan Pelaburan Luar Negara-i : sehingga 80% daripada nilai pelaburan<\/li><li>Pembiayaan Kontrak-i : sehingga 85% daripada nilai kontrak<\/li><\/ol><\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-21410\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"10\" aria-controls=\"elementor-tab-content-21410\">\n                                \n                <span style=\"width:100%\">Apakah Perbezaan di Antara Pembiayaan Pembeli-i dan Pembiayaan Projek Luar Negara-i?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-21410\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-21410\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\"><p>Pembiayaan Pembeli-i merupakan kemudahan pembiayaan yang ditawarkan kepada prinsipal asing\/pengimport barangan dan perkhidmatan Malaysia manakala Pembiayaan Projek Luar Negara-i ditawarkan kepada syarikat kawalan warganegara Malaysia yang terlibat dalam melaksanakan projek Luar Negara.<\/p><\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n        \n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-left \" tabindex=\"4772\" data-tab=\"2\" role=\"tab\"><span>Pembiayaan <br> Perdagangan<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"2\" role=\"tabpanel\"><div class=\"plus-content-editor\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9918\" class=\"elementor elementor-9918\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a4a39cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a4a39cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50e3b6bd\" data-id=\"50e3b6bd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5ad5e8 faq elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-tp-accordion\" data-id=\"c5ad5e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"theplus-accordion-wrapper elementor-accordion   \"\n    id=\"accordion6a03d04d2b1bf\" data-accordion-id=\"accordion6a03d04d2b1bf\"\n    data-connection=\"\"\n    data-accordion-type=\"accordion\"\n    data-heightlight-text       role=\"tablist\" >\n\n            <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2071\" class=\"elementor-tab-title plus-accordion-header active-default text-left \" data-tab=\"1\" aria-controls=\"elementor-tab-content-2071\">\n                                \n                <span style=\"width:100%\">Apakah yang Dimaksudkan dengan Pembiayaan Perdagangan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2071\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content active-default \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2071\">\n                <div class=\"plus-content-editor\" ><p>Pembiayaan perdagangan merupakan pembiayaan untuk transaksi perdagangan sama ada domestik atau perdagangan antarabangsa. Di EXIM Bank, kami hanya menyediakan pembiayaan untuk transaksi perdagangan antarabangsa. Transaksi perdagangan ini memerlukan penjual dan pembeli yang berdagang dengan barangan atau perkhidmatan sebagai perkara asas.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2072\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"2\" aria-controls=\"elementor-tab-content-2072\">\n                                \n                <span style=\"width:100%\">Apakah Produk Pembiayaan Perdagangan yang Ditawarkan oleh EXIM Bank?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2072\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2072\">\n                <div class=\"plus-content-editor\" ><ol><li>Pembiayaan Pembekal-i<\/li><li>Pembiayaan Semula Kredit Eksport-i<\/li><li>Pembiayaan IDB Co<\/li><li>Resit Amanah-i<\/li><li>Skim Pembiayaan Vendor-i<\/li><li>Surat Kredit-i<\/li><li>Pembelian Bil Pertukaran Asing-i<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2073\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"3\" aria-controls=\"elementor-tab-content-2073\">\n                                \n                <span style=\"width:100%\">Siapakah yang Layak untuk Memohon Produk Pembiayaan Perdagangan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2073\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2073\">\n                <div class=\"plus-content-editor\" ><p><strong>Pembiayaan Pembekal-i<\/strong><\/p><ol><li>Pengeksport Malaysia berdaftar di bawah Akta Syarikat 2016<\/li><li>Syarikat Kawalan Bukan Pemastautin<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembiayaan Semula Kredit Eksport-i<\/strong><\/p><ol><li>Syarikat yang diperbadankan di Malaysia dan terlibat secara langsung atau tidak langsung dalam aktiviti eksport dan perdagangan antarabangsa.<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembiayaan IDB Co<\/strong><\/p><ol><li>Pengimport\/Pembeli daripada Negara Ahli IDB (Islamic Development Bank\/Bank Pembangunan Islam) dengan tiga (3) tahun pengalaman dalam perniagaan dan Pengeskport Malaysia yang mengeksport barangan Malaysia.<\/li><\/ol><p>\u00a0<\/p><p><strong>Resit Amanah-i<\/strong><\/p><ol><li>Barangan import bernilai strategik adalah layak<\/li><li>Pembekal tempatan adalah tidak layak<\/li><li>Barangan import daripada ejen tempatan mungkin berkelayakan<\/li><\/ol><p>\u00a0<\/p><p><strong>Skim Pembiayaan Vendor-i<\/strong><\/p><ol><li>Syarikat perkilangan Malaysia yang terlibat dan \/ atau menyokong industri berkaitan eksport dalam Program Vendor terpilih<\/li><\/ol><p>\u00a0<\/p><p><strong>Surat Kredit-i<\/strong><\/p><ol><li>Pengeksport Malaysia berdaftar di bawah Akta Syarikat 2016<\/li><li>Syarikat Kawalan Bukan Pemastautin<\/li><\/ol><p>\u00a0<\/p><p><strong>Pembelian Bil Pertukaran Asing-i<\/strong><\/p><ol><li>Pengeksport Malaysia berdaftar di bawah Akta Syarikat 2016<\/li><li>Syarikat Kawalan Bukan Pemastautin<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2074\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"4\" aria-controls=\"elementor-tab-content-2074\">\n                                \n                <span style=\"width:100%\">Bagaimanakah Saya Boleh Memohon Produk Pembiayaan Perdagangan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2074\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2074\">\n                <div class=\"plus-content-editor\" ><p>Anda boleh menghubungi kami di +603-2601 2000 untuk bercakap dengan Pengurus Perhubungan untuk maklumat lanjut.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2075\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"5\" aria-controls=\"elementor-tab-content-2075\">\n                                \n                <span style=\"width:100%\">Apakah Konsep Syariah yang Diguna Pakai Dalam Produk Pembiayaan Perdagangan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2075\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2075\">\n                <div class=\"plus-content-editor\" ><ol><li>Ijarah<\/li><li>Istisna\u2019<\/li><li>Murabahah<\/li><li>Tawarruq (Komoditi Murabahah)<\/li><li>Wakalah<\/li><li>Kafalah<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2076\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"6\" aria-controls=\"elementor-tab-content-2076\">\n                                \n                <span style=\"width:100%\">Berapakah Kos untuk Memohon Pembiayaan Perdagangan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2076\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2076\">\n                <div class=\"plus-content-editor\" ><p>Anda boleh rujuk kepada\u00a0<a class=\"docs-creator\" href=\"https:\/\/exim.com.my\/development\/documents\/quick-links\/fee-charges\/Fees-and-Charges-for-Islamic-Products%26Services_2020_BM.pdf\" target=\"_blank\" rel=\"noopener\">Fi dan Caj Standard untuk Produk Pembiayaan Perdagangan<\/a>\u00a0untuk fi dan caj terperinci atau hubungi kami di +603-2601 2000 untuk bercakap dengan Pengurus Perhubungan untuk maklumat lanjut.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2077\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"7\" aria-controls=\"elementor-tab-content-2077\">\n                                \n                <span style=\"width:100%\">Apakah Surat Kredit-<em>i<\/em>?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2077\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2077\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\">Surat Kredit-<em>i<\/em> merupakan kaedah selamat untuk memastikan pembayaran segera untuk barangan yang dieksport dalam pasaran antarabangsa dan distruktur berdasarkan kontrak Syariah Wakalah dan Murabahah.<\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2078\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"8\" aria-controls=\"elementor-tab-content-2078\">\n                                \n                <span style=\"width:100%\">Berapa Lamakah Masa yang Diambil oleh EXIM Bank untuk Memproses dan Menyampaikan Keputusan Keatas Permohonan Pembiayaan Perdagangan ?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-2078\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2078\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\">Biasanya ia mengambil masa kira-kira 20 hari daripada tarikh permohonan (tertakluk kepada maklumat dan dokumen lengkap yang dikemukakan).<\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n        \n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-left \" tabindex=\"4773\" data-tab=\"3\" role=\"tab\"><span>Jaminan<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"3\" role=\"tabpanel\"><div class=\"plus-content-editor\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9921\" class=\"elementor elementor-9921\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a4a39cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a4a39cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50e3b6bd\" data-id=\"50e3b6bd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73a33fd faq elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-tp-accordion\" data-id=\"73a33fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"theplus-accordion-wrapper elementor-accordion   \"\n    id=\"accordion6a03d04d4ab30\" data-accordion-id=\"accordion6a03d04d4ab30\"\n    data-connection=\"\"\n    data-accordion-type=\"accordion\"\n    data-heightlight-text       role=\"tablist\" >\n\n            <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1211\" class=\"elementor-tab-title plus-accordion-header active-default text-left \" data-tab=\"1\" aria-controls=\"elementor-tab-content-1211\">\n                                \n                <span style=\"width:100%\">Adakah EXIM Bank Menawarkan Kemudahan Jaminan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1211\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content active-default \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1211\">\n                <div class=\"plus-content-editor\" ><p>Ya, kami ada menyediakan kemudahan Jaminan Bank-<em>i<\/em> kepada pelanggan kami.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1212\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"2\" aria-controls=\"elementor-tab-content-1212\">\n                                \n                <span style=\"width:100%\">Apakah Jaminan Bank-<em>i<\/em>?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1212\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1212\">\n                <div class=\"plus-content-editor\" ><p>Jaminan Bank-<em>i<\/em> merupakan kemudahan jaminan disediakan oleh EXIM Bank kepada pemiutang\/prinsipal ke atas tanggungan penghutang\/penanggung diperincikan dalam kontrak di antara pemiutang\/prinsipal dan penghutang\/penanggung.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1213\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"3\" aria-controls=\"elementor-tab-content-1213\">\n                                \n                <span style=\"width:100%\">Apakah Kontrak Syariah yang Diguna Pakai untuk Jaminan Bank-<em>i<\/em>?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1213\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1213\">\n                <div class=\"plus-content-editor\" ><p>Kontrak Syariah yang diguna pakai untuk Jaminan Bank-<em>i<\/em> ialah Kafalah.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1214\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"4\" aria-controls=\"elementor-tab-content-1214\">\n                                \n                <span style=\"width:100%\">Apakah Jenis Kemudahan Jaminan Ditawarkan oleh EXIM Bank?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1214\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1214\">\n                <div class=\"plus-content-editor\" ><ol><li>Jaminan Tender\/Bon Bida<\/li><li>Jaminan Prestasi\/Kontrak<\/li><li>Jaminan Bayaran Pendahuluan<\/li><li>Surat Kredit Tersedia<\/li><li>Jaminan Perkapalan \/ Pengesahan Bil Muatan (BL) atau Bil Jalan Udara (AWB)<\/li><li>Bon Jaminan<\/li><li>Bon Pengembalian<\/li><li>Bon Kastam<\/li><li>Jaminan Kredit \/ Jaminan Bekalan<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1215\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"5\" aria-controls=\"elementor-tab-content-1215\">\n                                \n                <span style=\"width:100%\">Berapakah Kos Untuk Memohon Jaminan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1215\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1215\">\n                <div class=\"plus-content-editor\" ><p>Anda boleh rujuk kepada\u00a0<a class=\"docs-creator\" href=\"https:\/\/exim.com.my\/development\/documents\/quick-links\/fee-charges\/Fees-and-Charges-for-Islamic-Products%26Services_2020_BM.pdf\" target=\"_blank\" rel=\"noopener\">Fi dan Caj Standard untuk Produk Pembiayaan Perdagangan<\/a>\u00a0untuk fi dan caj terperinci atau hubungi kami di +603-2601 2000 untuk bercakap dengan Pengurus Perhubungan untuk maklumat lanjut.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1216\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"6\" aria-controls=\"elementor-tab-content-1216\">\n                                \n                <span style=\"width:100%\">Bagaimanakah Saya Boleh Memohon Produk Jaminan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1216\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1216\">\n                <div class=\"plus-content-editor\" ><p>Anda boleh menghubungi kami di +603-2601 2000 untuk bercakap dengan Pengurus Perhubungan untuk maklumat lanjut.<\/p><\/div>\n            <\/div>\n                    <\/div>\n        \n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><div class=\"elementor-tab-title elementor-tab-mobile-title text-left \" tabindex=\"4774\" data-tab=\"4\" role=\"tab\"><span>Takaful <br> Kredit<\/span><\/div><div class=\"elementor-tab-content elementor-clearfix plus-tab-content\" data-tab=\"4\" role=\"tabpanel\"><div class=\"plus-content-editor\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9922\" class=\"elementor elementor-9922\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a4a39cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3a4a39cc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ob_glider_is_slider&quot;:&quot;no&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50e3b6bd\" data-id=\"50e3b6bd\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ebc4b6 faq elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-tp-accordion\" data-id=\"8ebc4b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;}\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"theplus-accordion-wrapper elementor-accordion   \"\n    id=\"accordion6a03d04d6dd72\" data-accordion-id=\"accordion6a03d04d6dd72\"\n    data-connection=\"\"\n    data-accordion-type=\"accordion\"\n    data-heightlight-text       role=\"tablist\" >\n\n            <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1491\" class=\"elementor-tab-title plus-accordion-header active-default text-left \" data-tab=\"1\" aria-controls=\"elementor-tab-content-1491\">\n                                \n                <span style=\"width:100%\">Apakah yang Dimaksudkan dengan Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1491\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content active-default \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1491\">\n                <div class=\"plus-content-editor\" ><p>Takaful Kredit memberikan perlindungan terhadap risiko pembayaran yang tidak dibayar oleh pembeli akibat dari risiko komersial dan \/ atau politik. Credit Takaful adalah kemudahan paling penting bagi Pengeksport Malaysia untuk mendapatkan bayaran untuk eksport dan import mereka sama ada dari pembeli atau dari EXIM Bank melalui tuntutan Takaful.<\/p><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1492\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"2\" aria-controls=\"elementor-tab-content-1492\">\n                                \n                <span style=\"width:100%\">Apakah Produk Takaful Kredit yang Ditawarkan oleh EXIM Bank?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1492\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1492\">\n                <div class=\"plus-content-editor\" ><ol><li>Takaful Kredit Pedagangan<\/li><li>Takaful Kredit Bank<\/li><li>Takaful Spesifik<\/li><li>Takaful Pelaburan Luar Negara<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1493\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"3\" aria-controls=\"elementor-tab-content-1493\">\n                                \n                <span style=\"width:100%\">Siapakah yang Layak untuk Memohon Produk Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1493\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1493\">\n                <div class=\"plus-content-editor\" ><p><strong>Takaful Kredit Pedagangan<\/strong><\/p><ol><li>Syarikat diperbadankan di Malasyia berdaftar dibawah Akta Syarikat 2016 termasuk Bank dan Institusi Kewangan yang lain contohnya syarikat pemfaktoran<\/li><li>Pengeksport mesti terlibat dalam perniagaan eksport. Tiada jumlah minimum.<\/li><li>Minimum 2 tahun beroperasi.<\/li><li>Tiada rekod prestasi yang tidak elok dalam pengkalan data kredit.<\/li><li>Modal berbayar minimum sebanyak RM100, 000.<\/li><li>Bukti eksport dalam tempoh 12 bulan sebelumnya.<\/li><\/ol><p>\u00a0<\/p><p><strong>Takaful Kredit Perdagangan Bank<\/strong><\/p><ol><li>Institusi Kewangan Islam (IKI) terhadap risiko tidak membayar oleh pengeksport mereka yang timbul daripada kegagalan pembeli luar negara.<\/li><\/ol><p>\u00a0<\/p><p><strong>Takaful Spesifik<\/strong><\/p><ol><li>Kontraktor dan pengilang Malaysia yang melaksanakan kontrak untuk eksport barangan modal, projek turnkey, kerja pembinaan, atau perkhidmatan yang diberikan di Luar Negara.<\/li><\/ol><p>\u00a0<\/p><p><strong>Takaful Pelaburan Luar Negara<\/strong><\/p><ol><li>Syarikat yang diperbadankan dan mempunyai perniagaan teras di Malaysia termasuk Institusi Kewangan yang membiayai Projek\/Pelaburan luar Negara.<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1494\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"4\" aria-controls=\"elementor-tab-content-1494\">\n                                \n                <span style=\"width:100%\">Siapakah yang Memerlukan Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1494\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1494\">\n                <div class=\"plus-content-editor\" ><ol><li>Pengeksport Malaysia<\/li><li>Kontraktor Malaysia<\/li><li>Pelabur Malaysia<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1495\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"5\" aria-controls=\"elementor-tab-content-1495\">\n                                \n                <span style=\"width:100%\">Apakah Terma Bayaran yang Diterima untuk Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1495\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1495\">\n                <div class=\"plus-content-editor\" ><ol><li>Surat Kredit Tidak boleh batal (ILC)<\/li><li>Dokumen Terhadap Pembayaran (DP)<\/li><li>Dokumen Terhadap Penerimaan (DA)<\/li><li>Akaun Terbuka (OA)<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1496\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"6\" aria-controls=\"elementor-tab-content-1496\">\n                                \n                <span style=\"width:100%\">Apakah Kontrak Syariah Diguna Pakai Dalam Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1496\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1496\">\n                <div class=\"plus-content-editor\" ><ol><li>Wakalah<\/li><li>Mudarabah<\/li><li>Tabarru\u2019<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1497\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"7\" aria-controls=\"elementor-tab-content-1497\">\n                                \n                <span style=\"width:100%\">Negara Manakah Tersenarai di Bawah Negara-negara yang Tidak Dilindungi?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1497\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1497\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\"><ol><li>Afghanistan<\/li><li>Libya<\/li><li>Lebanon<\/li><li>Israel<\/li><li>Syria<\/li><li>Iran<\/li><li>Korea Utara<\/li><li>Seychelles<\/li><li>Tunisia<\/li><li>Yemen<\/li><li>Mesir<\/li><\/ol><\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1498\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"8\" aria-controls=\"elementor-tab-content-1498\">\n                                \n                <span style=\"width:100%\">Bagaimanakah Cara untuk Memohon Produk Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1498\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1498\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\">Anda boleh menghubungi kami di +603-2601 2000 untuk bercakap dengan Pengurus Perhubungan untuk maklumat lanjut.<\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1499\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"9\" aria-controls=\"elementor-tab-content-1499\">\n                                \n                <span style=\"width:100%\">Kenapa Saya Perlukan Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-1499\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1499\">\n                <div class=\"plus-content-editor\" ><p>Takaful Kredit boleh menjamin pembayaran untuk eksport and import anda. Anda akan memperoleh perlindungan terhadap risiko tidak membayar oleh pembeli. Manfaat takaful kredit adalah:<\/p><ol><li>Ketenangan fikiran kerana pembayaran adalah terjamin<\/li><li>Membolehkan pengeksport Malaysia untuk meneroka pasaran baharu<\/li><li>Perkongsian keuntungan pelaburan<\/li><\/ol><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-14910\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"10\" aria-controls=\"elementor-tab-content-14910\">\n                                \n                <span style=\"width:100%\">Berapakah Kos untuk Memohon Produk Takaful Kredit?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-14910\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"10\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-14910\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\"><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\">Anda boleh rujuk kepada\u00a0<a class=\"docs-creator\" href=\"https:\/\/exim.com.my\/development\/documents\/quick-links\/fee-charges\/F&amp;C-Credit-Takaful-BM.pdf\" target=\"_blank\" rel=\"noopener\">Fi dan Caj Standard untuk Produk Takaful Kredit<\/a>\u00a0untuk fi dan caj terperinci atau hubungi kami di +603-2601 2000 untuk bercakap dengan Pengurus Perhubungan untuk maklumat lanjut.<\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-14911\" class=\"elementor-tab-title plus-accordion-header no text-left \" data-tab=\"11\" aria-controls=\"elementor-tab-content-14911\">\n                                \n                <span style=\"width:100%\">Berapa Lamakah Masa yang Diambil oleh EXIM Bank untuk Memproses dan Menyampaikan Keputusan Keatas Permohonan Pembiayaan Rentas Sempadan?<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-plus\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-minus\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-14911\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content no \" data-tab=\"11\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-14911\">\n                <div class=\"plus-content-editor\" ><div data-wrapper=\"true\" aria-expanded=\"true\"><div class=\"uk-accordion-content uk-active\"><div class=\"uk-margin\"><ol><li>Takaful kredit berjangka sederhana-panjang : 45 hari*<\/li><li>Takaful kredit jangka pendek : 15 hari*<\/li><\/ol><p>*tertakluk kepada maklumat dan dokumen lengkap yang dikemukakan<\/p><\/div><\/div><\/div><\/div>\n            <\/div>\n                    <\/div>\n        \n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Berita dan Peristiwa Kenyataan Akhbar Laporan Tahunan Galeri Multimedia Tinjauan Soalan Lazim SOALAN LAZIM Rentas Sempadan Pembiayaan Perdagangan Jaminan Takaful Kredit Rentas Sempadan Apakah yang Dimaksudkan dengan Pembiayaan Rentas Sempadan? Kemudahan pembiayaan yang diberikan kepada pelanggan yang berhasrat menceburi dalam perniagaan rentas sempadan. Pakah Produk Pembiayaan Rentas Sempadan yang Ditawarkan oleh EXIM Bank? Pembiayaan Projek\/Pelaburan [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-9781","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/pages\/9781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/comments?post=9781"}],"version-history":[{"count":1,"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/pages\/9781\/revisions"}],"predecessor-version":[{"id":12642,"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/pages\/9781\/revisions\/12642"}],"wp:attachment":[{"href":"https:\/\/exim.com.my\/development\/wp-json\/wp\/v2\/media?parent=9781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}